{"id":538027,"date":"2025-04-15T09:15:17","date_gmt":"2025-04-15T09:15:17","guid":{"rendered":"https:\/\/harristweed-shop.be\/product\/harris-tweed-vestje-816\/"},"modified":"2026-05-05T04:00:48","modified_gmt":"2026-05-05T04:00:48","slug":"harris-tweed-vestje-816","status":"publish","type":"product","link":"https:\/\/harristweed-shop.be\/fr\/produit\/gilet-en-tweed-harris-816\/","title":{"rendered":"Gilet en tweed Harris Wales avec revers en Blackwatch"},"content":{"rendered":"<p>Gilet Harris Tweed \u00ab Wales \u00bb \u2013 pour les hommes avec style, raffinement et sens de la tradition.<\/p>\n<p>\u00ab L&#039;un des plus beaux tweeds au monde \u00bb \u2013 Le Harris Tweed m\u00e9rite cette distinction \u00e0 juste titre. Le gilet classique \u00ab Wales \u00bb pour homme, confectionn\u00e9 en laine vierge 100%, allie savoir-faire traditionnel et polyvalence moderne. Tiss\u00e9 \u00e0 la main dans les H\u00e9brides ext\u00e9rieures \u00e9cossaises, le Harris Tweed exclusif est bien plus qu&#039;un simple tissu\u00a0: c&#039;est une tradition vivante, un savoir-faire authentique et un t\u00e9moignage de l&#039;histoire culturelle britannique. Depuis plus d&#039;un si\u00e8cle, Harris Tweed est synonyme de qualit\u00e9 authentique et d&#039;une production durable et naturelle in\u00e9gal\u00e9e. Le Harris Tweed est non seulement esth\u00e9tique, mais aussi fonctionnel\u00a0: respirant, thermor\u00e9gulateur et durable, il offre un confort supr\u00eame, toute l&#039;ann\u00e9e\u00a0!<\/p>\n<p>Avec son \u00e9l\u00e9gant col \u00e0 revers et son dos confectionn\u00e9s dans le m\u00eame tissu ext\u00e9rieur de haute qualit\u00e9, ce cardigan d\u00e9gage une \u00e9l\u00e9gance intemporelle. Cinq boutons effet corne raffin\u00e9e, deux poches \u00e0 rabat classiques, une poche poitrine authentique et une poche int\u00e9rieure pratique soulignent son design \u00e9l\u00e9gant. Gr\u00e2ce \u00e0 sa bride arri\u00e8re r\u00e9glable, la coupe s&#039;ajuste individuellement, pour une tenue parfaite en toute occasion.<\/p>\n<p>Qu&#039;il soit associ\u00e9 \u00e0 la veste Harris Tweed assortie \u00ab London \u00bb, de mani\u00e8re d\u00e9contract\u00e9e avec un jean ou classique avec un chino et un pantalon en velours c\u00f4tel\u00e9, le gilet \u00ab Wales \u00bb s&#039;av\u00e8re \u00eatre un v\u00eatement polyvalent avec du caract\u00e8re et est une expression de style, de qualit\u00e9 et d&#039;individualit\u00e9.<\/p>\n<p>\u2013 100% pure laine vierge<br \/>\u2013 une poche de poitrine<br \/>\u2013 une poche int\u00e9rieure<br \/>\u2013 doublure color\u00e9e<br \/>\u2013 l\u00e9g\u00e8rement ajust\u00e9<br \/>\u2013 col \u00e0 revers<br \/>\u2013 Devant et dos enti\u00e8rement en Harris Tweed<br \/>&nbsp; &nbsp; sangle r\u00e9glable \u00e0 l&#039;arri\u00e8re<br \/>\u2013 deux poches \u00e0 rabat et une poche ticket sur le c\u00f4t\u00e9 droit<\/p>\n<p>Taille du mod\u00e8le : Le mannequin mesure 189 cm et porte la taille 50.<br \/>Coupe : Cardigan ajust\u00e9, coupe moderne, ajustable individuellement gr\u00e2ce \u00e0 la sangle r\u00e9glable au dos.<br \/>Taille de l&#039;article : Pour la taille 50, les mesures sont : longueur dos : 61 cm \u2013 demi-poitrine : 55 cm \u2013 demi-taille : 53 cm.<\/p>\n<p>Tissu ext\u00e9rieur : laine vierge 100%<br \/>Doublure : 55% polyester, 45% viscose<\/p>","protected":false},"excerpt":{"rendered":"<p>Gilet en tweed Harris Wales avec revers en Blackwatch 816.<\/p>\n<p>Le gilet classique \u201c\u00a0Wales\u00a0\u201d pour homme, confectionn\u00e9 en laine vierge 100%, allie savoir-faire traditionnel et polyvalence moderne. Tiss\u00e9 \u00e0 la main dans les H\u00e9brides ext\u00e9rieures \u00e9cossaises, l\u2019exclusif Harris Tweed est bien plus qu\u2019un simple tissu\u00a0: c\u2019est une tradition vivante, un artisanat authentique et un pan du patrimoine culturel britannique.<\/p>","protected":false},"featured_media":538028,"template":"","meta":[],"product_brand":[],"product_cat":[1088,1156,510,1078,512,88,511],"product_tag":[],"class_list":{"0":"post-538027","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-harris-tweed-vestjes-en-gilets-heren","7":"product_cat-harris-tweed-westen-und-gilets-herren","8":"product_cat-heren-vestjes","9":"product_cat-heren-vestjes-harris-tweed","10":"product_cat-herren-westen-und-gilets","11":"product_cat-vestjes-en-gilets","12":"product_cat-westen-und-gilets","13":"pa_merk-harristweed","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-variable"},"df_price":179.95,"df_sale_price":"","df_regular_price":179.95,"df_image_link":"https:\/\/harristweed-shop.be\/wp-content\/uploads\/2025\/04\/5d2d170019c2b664197e0cfbbf7bfff6_Harris_Tweed_Vestje_816-225x300.jpg","_links":{"self":[{"href":"https:\/\/harristweed-shop.be\/fr\/wp-json\/wp\/v2\/product\/538027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/harristweed-shop.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/harristweed-shop.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/harristweed-shop.be\/fr\/wp-json\/wp\/v2\/media\/538028"}],"wp:attachment":[{"href":"https:\/\/harristweed-shop.be\/fr\/wp-json\/wp\/v2\/media?parent=538027"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/harristweed-shop.be\/fr\/wp-json\/wp\/v2\/product_brand?post=538027"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/harristweed-shop.be\/fr\/wp-json\/wp\/v2\/product_cat?post=538027"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/harristweed-shop.be\/fr\/wp-json\/wp\/v2\/product_tag?post=538027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}